{"id":26607,"date":"2023-08-22T07:49:00","date_gmt":"2023-08-22T07:49:00","guid":{"rendered":"https:\/\/www.cappellidesign.com\/?post_type=work&#038;p=26607"},"modified":"2025-02-25T13:34:17","modified_gmt":"2025-02-25T13:34:17","slug":"psicodizione","status":"publish","type":"work","link":"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/","title":{"rendered":"PSICODIZIONE"},"excerpt":{"rendered":"<p>Il cambiamento \u00e8 crescita.<br \/>\nLo abbiamo reso forma. <\/p>\n","protected":false},"author":12,"featured_media":26611,"template":"single-work-new-template.php","services":[162,120,139,141,144,143,156,150,432],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PSICODIZIONE - Cappelli Identity Design<\/title>\n<meta name=\"description\" content=\"La nuova brand identity Psicodizione incarna il potenziale espressivo delle persone che superano la balbuzie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PSICODIZIONE - Cappelli Identity Design\" \/>\n<meta property=\"og:description\" content=\"La nuova brand identity Psicodizione incarna il potenziale espressivo delle persone che superano la balbuzie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/\" \/>\n<meta property=\"og:site_name\" content=\"Cappelli Identity Design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cappellidesign\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T13:34:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cappellidesign.com\/wp-content\/uploads\/2023\/08\/CID_Psicodizione_COVER.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cappellidesign\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/\",\"url\":\"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/\",\"name\":\"PSICODIZIONE - Cappelli Identity Design\",\"isPartOf\":{\"@id\":\"https:\/\/www.cappellidesign.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cappellidesign.com\/wp-content\/uploads\/2023\/08\/CID_Psicodizione_COVER.png\",\"datePublished\":\"2023-08-22T07:49:00+00:00\",\"dateModified\":\"2025-02-25T13:34:17+00:00\",\"description\":\"La nuova brand identity Psicodizione incarna il potenziale espressivo delle persone che superano la balbuzie.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/#primaryimage\",\"url\":\"https:\/\/www.cappellidesign.com\/wp-content\/uploads\/2023\/08\/CID_Psicodizione_COVER.png\",\"contentUrl\":\"https:\/\/www.cappellidesign.com\/wp-content\/uploads\/2023\/08\/CID_Psicodizione_COVER.png\",\"width\":1920,\"height\":1080,\"caption\":\"Psicodizione Dynamic brand 2023\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cappellidesign.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\",\"item\":\"https:\/\/www.cappellidesign.com\/it\/progetti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PSICODIZIONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cappellidesign.com\/it\/#website\",\"url\":\"https:\/\/www.cappellidesign.com\/it\/\",\"name\":\"Cappelli Identity Design\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cappellidesign.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cappellidesign.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cappellidesign.com\/it\/#organization\",\"name\":\"Cappelli Identity Design\",\"url\":\"https:\/\/www.cappellidesign.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.cappellidesign.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cappellidesign.com\/wp-content\/uploads\/2019\/12\/cappellidesign_logo.svg\",\"contentUrl\":\"https:\/\/www.cappellidesign.com\/wp-content\/uploads\/2019\/12\/cappellidesign_logo.svg\",\"width\":369,\"height\":17,\"caption\":\"Cappelli Identity Design\"},\"image\":{\"@id\":\"https:\/\/www.cappellidesign.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cappellidesign\/\",\"https:\/\/x.com\/cappellidesign\",\"https:\/\/www.instagram.com\/cappellidesign\",\"https:\/\/www.linkedin.com\/company\/cappelli-identity-design\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PSICODIZIONE - Cappelli Identity Design","description":"La nuova brand identity Psicodizione incarna il potenziale espressivo delle persone che superano la balbuzie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/","og_locale":"it_IT","og_type":"article","og_title":"PSICODIZIONE - Cappelli Identity Design","og_description":"La nuova brand identity Psicodizione incarna il potenziale espressivo delle persone che superano la balbuzie.","og_url":"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/","og_site_name":"Cappelli Identity Design","article_publisher":"https:\/\/www.facebook.com\/cappellidesign\/","article_modified_time":"2025-02-25T13:34:17+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.cappellidesign.com\/wp-content\/uploads\/2023\/08\/CID_Psicodizione_COVER.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@cappellidesign","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/","url":"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/","name":"PSICODIZIONE - Cappelli Identity Design","isPartOf":{"@id":"https:\/\/www.cappellidesign.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/#primaryimage"},"image":{"@id":"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cappellidesign.com\/wp-content\/uploads\/2023\/08\/CID_Psicodizione_COVER.png","datePublished":"2023-08-22T07:49:00+00:00","dateModified":"2025-02-25T13:34:17+00:00","description":"La nuova brand identity Psicodizione incarna il potenziale espressivo delle persone che superano la balbuzie.","breadcrumb":{"@id":"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/#primaryimage","url":"https:\/\/www.cappellidesign.com\/wp-content\/uploads\/2023\/08\/CID_Psicodizione_COVER.png","contentUrl":"https:\/\/www.cappellidesign.com\/wp-content\/uploads\/2023\/08\/CID_Psicodizione_COVER.png","width":1920,"height":1080,"caption":"Psicodizione Dynamic brand 2023"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cappellidesign.com\/it\/progetti\/psicodizione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cappellidesign.com\/it\/"},{"@type":"ListItem","position":2,"name":"Progetti","item":"https:\/\/www.cappellidesign.com\/it\/progetti\/"},{"@type":"ListItem","position":3,"name":"PSICODIZIONE"}]},{"@type":"WebSite","@id":"https:\/\/www.cappellidesign.com\/it\/#website","url":"https:\/\/www.cappellidesign.com\/it\/","name":"Cappelli Identity Design","description":"","publisher":{"@id":"https:\/\/www.cappellidesign.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cappellidesign.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.cappellidesign.com\/it\/#organization","name":"Cappelli Identity Design","url":"https:\/\/www.cappellidesign.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.cappellidesign.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.cappellidesign.com\/wp-content\/uploads\/2019\/12\/cappellidesign_logo.svg","contentUrl":"https:\/\/www.cappellidesign.com\/wp-content\/uploads\/2019\/12\/cappellidesign_logo.svg","width":369,"height":17,"caption":"Cappelli Identity Design"},"image":{"@id":"https:\/\/www.cappellidesign.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cappellidesign\/","https:\/\/x.com\/cappellidesign","https:\/\/www.instagram.com\/cappellidesign","https:\/\/www.linkedin.com\/company\/cappelli-identity-design\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.cappellidesign.com\/it\/wp-json\/wp\/v2\/work\/26607"}],"collection":[{"href":"https:\/\/www.cappellidesign.com\/it\/wp-json\/wp\/v2\/work"}],"about":[{"href":"https:\/\/www.cappellidesign.com\/it\/wp-json\/wp\/v2\/types\/work"}],"author":[{"embeddable":true,"href":"https:\/\/www.cappellidesign.com\/it\/wp-json\/wp\/v2\/users\/12"}],"version-history":[{"count":5,"href":"https:\/\/www.cappellidesign.com\/it\/wp-json\/wp\/v2\/work\/26607\/revisions"}],"predecessor-version":[{"id":37894,"href":"https:\/\/www.cappellidesign.com\/it\/wp-json\/wp\/v2\/work\/26607\/revisions\/37894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cappellidesign.com\/it\/wp-json\/wp\/v2\/media\/26611"}],"wp:attachment":[{"href":"https:\/\/www.cappellidesign.com\/it\/wp-json\/wp\/v2\/media?parent=26607"}],"wp:term":[{"taxonomy":"services","embeddable":true,"href":"https:\/\/www.cappellidesign.com\/it\/wp-json\/wp\/v2\/services?post=26607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}